{"id":12,"date":"2023-10-10T16:03:23","date_gmt":"2023-10-10T14:03:23","guid":{"rendered":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/?page_id=12"},"modified":"2024-01-11T10:27:06","modified_gmt":"2024-01-11T09:27:06","slug":"elementor-12","status":"publish","type":"page","link":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12\" class=\"elementor elementor-12\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cfd763 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3cfd763\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3356fde\" data-id=\"3356fde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17b8dbb elementor-widget elementor-widget-image\" data-id=\"17b8dbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"768\" src=\"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-1536x768.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-134\" alt=\"\" srcset=\"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-1536x768.jpg 1536w, http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-300x150.jpg 300w, http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-1024x512.jpg 1024w, http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-768x384.jpg 768w, http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-2048x1024.jpg 2048w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32348e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"32348e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3546de\" data-id=\"e3546de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db350e3 elementor-widget elementor-widget-spacer\" data-id=\"db350e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99f6dcd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"99f6dcd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c1a477\" data-id=\"2c1a477\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f66f756 elementor-widget elementor-widget-heading\" data-id=\"f66f756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\">Bienvenue sur mon site <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e04d2b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e04d2b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1fadad\" data-id=\"e1fadad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-204b870 elementor-widget elementor-widget-spacer\" data-id=\"204b870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-138a010 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"138a010\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aba0f2d\" data-id=\"aba0f2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd69f6a elementor-widget elementor-widget-heading\" data-id=\"fd69f6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qui suis-je ? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fed766a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"fed766a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01cdb80\" data-id=\"01cdb80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-536fa7c elementor-widget elementor-widget-text-editor\" data-id=\"536fa7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je m&rsquo;appelle J\u00e9r\u00f4me, j&rsquo;ai 23 ans et suis \u00e9tudiant en Bachelor de Gestion et Valorisation de la Nature.&nbsp;<span style=\"font-family: Arial, sans-serif;font-size: 12pt;text-align: justify;color: var( --e-global-color-text );font-weight: var( --e-global-typography-text-font-weight );background-color: var(--nv-site-bg);letter-spacing: var(--bodyletterspacing);text-transform: var(--bodytexttransform)\">Ayant v\u00e9cu en Afrique pendant 15 ans, j&rsquo;ai pu r\u00e9sider et voyager dans diff\u00e9rents pays tels que le Congo, le Burkina Faso, le B\u00e9nin et d&rsquo;autres. Cette exp\u00e9rience m&rsquo;a permis d&rsquo;avoir eu&nbsp;<\/span><span style=\"color: var( --e-global-color-text );font-weight: var( --e-global-typography-text-font-weight );font-size: 12pt;letter-spacing: var(--bodyletterspacing);text-transform: var(--bodytexttransform);font-family: Arial, sans-serif;background-color: var(--nv-site-bg)\">r\u00e9guli\u00e8rement la chance de pouvoir suivre des organisations priv\u00e9es et des ONG sp\u00e9cialis\u00e9es dans la pr\u00e9servation de l\u2019environnement et plus particuli\u00e8rement la conservation animale. <\/span><span style=\"color: var( --e-global-color-text );font-weight: var( --e-global-typography-text-font-weight );font-size: 12pt;letter-spacing: var(--bodyletterspacing);text-transform: var(--bodytexttransform);font-family: Arial, sans-serif;background-color: var(--nv-site-bg)\">Je peux dire que ce v\u00e9cu m\u2019a permis d\u2019acqu\u00e9rir le savoir de la hi\u00e9rarchie et de la discipline.&nbsp;<\/span><span style=\"color: var( --e-global-color-text );font-size: 12pt;letter-spacing: var(--bodyletterspacing);text-transform: var(--bodytexttransform);font-family: Arial, sans-serif;background-color: var(--nv-site-bg)\">Je pratique aussi beaucoup de sport en dehors du campus, notamment la boxe et la musculation qui en plusieurs ann\u00e9es de pratique, me sont devenues indispensables. D\u2019un temp\u00e9rament plut\u00f4t autonome, ces discipline m\u2019ont permis de d\u00e9velopper le go\u00fbt de la pers\u00e9v\u00e9rance, de la rigueur et du respect. Je souhaiterais donc continuer \u00e0 travailler dans la conservation apr\u00e8s mon Master, en retournant en Afrique ou en d\u00e9couvrant de nouveaux pays du Monde.&nbsp;<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5823a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5823a09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e58675c\" data-id=\"e58675c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30e084b elementor-widget elementor-widget-text-editor\" data-id=\"30e084b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Suivez-moi sur les r\u00e9seaux :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1b914c elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"f1b914c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-1c65e0d\" href=\"https:\/\/www.instagram.com\/rothjerome.pro\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-282f688\" href=\"http:\/\/www.linkedin.com\/in\/j\u00e9r\u00f4me-roth\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d65645 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4d65645\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a33d33\" data-id=\"1a33d33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2a4638 elementor-widget elementor-widget-spacer\" data-id=\"f2a4638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11a6919 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"11a6919\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35b58df\" data-id=\"35b58df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5a36f9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f5a36f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/diderot.education\/65254e4a287a2-jerome-roth\/experiencesprofessionnelles\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Exp\u00e9riences Professionnelles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dd970fe\" data-id=\"dd970fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0762bbe elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0762bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/diderot.education\/65254e4a287a2-jerome-roth\/formations\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Formations<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-85c7187\" data-id=\"85c7187\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b71e1a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4b71e1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/diderot.education\/65254e4a287a2-jerome-roth\/cv\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CV<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7803cb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c7803cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-747f7da\" data-id=\"747f7da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86cc8a1 elementor-widget elementor-widget-spacer\" data-id=\"86cc8a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bienvenue sur mon site Qui suis-je ? Je m&rsquo;appelle J\u00e9r\u00f4me, j&rsquo;ai 23 ans et suis \u00e9tudiant en Bachelor de Gestion et Valorisation de la Nature.&nbsp;Ayant v\u00e9cu en Afrique pendant 15 ans, j&rsquo;ai pu r\u00e9sider et voyager dans diff\u00e9rents pays tels que le Congo, le Burkina Faso, le B\u00e9nin et d&rsquo;autres. Cette exp\u00e9rience m&rsquo;a permis d&rsquo;avoir eu&nbsp;r\u00e9guli\u00e8rement la chance de pouvoir suivre des organisations priv\u00e9es et des ONG sp\u00e9cialis\u00e9es dans la pr\u00e9servation de l\u2019environnement et plus particuli\u00e8rement la conservation animale. Je peux dire que ce v\u00e9cu m\u2019a permis d\u2019acqu\u00e9rir le savoir de la hi\u00e9rarchie et de la discipline.&nbsp;Je pratique aussi beaucoup de sport en dehors du campus, notamment la boxe et la musculation qui en plusieurs ann\u00e9es de pratique, me sont devenues indispensables. D\u2019un temp\u00e9rament plut\u00f4t autonome, ces discipline m\u2019ont permis de d\u00e9velopper le go\u00fbt de la pers\u00e9v\u00e9rance, de la rigueur et du respect. Je souhaiterais donc continuer \u00e0 travailler dans la conservation apr\u00e8s mon Master, en retournant en Afrique ou en d\u00e9couvrant de nouveaux pays du Monde.&nbsp; Suivez-moi sur les r\u00e9seaux : Instagram Linkedin Exp\u00e9riences Professionnelles Formations CV<\/p>\n","protected":false},"author":348,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - J\u00e9r\u00f4me ROTH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - J\u00e9r\u00f4me ROTH\" \/>\n<meta property=\"og:description\" content=\"Bienvenue sur mon site Qui suis-je ? Je m&rsquo;appelle J\u00e9r\u00f4me, j&rsquo;ai 23 ans et suis \u00e9tudiant en Bachelor de Gestion et Valorisation de la Nature.&nbsp;Ayant v\u00e9cu en Afrique pendant 15 ans, j&rsquo;ai pu r\u00e9sider et voyager dans diff\u00e9rents pays tels que le Congo, le Burkina Faso, le B\u00e9nin et d&rsquo;autres. Cette exp\u00e9rience m&rsquo;a permis d&rsquo;avoir eu&nbsp;r\u00e9guli\u00e8rement la chance de pouvoir suivre des organisations priv\u00e9es et des ONG sp\u00e9cialis\u00e9es dans la pr\u00e9servation de l\u2019environnement et plus particuli\u00e8rement la conservation animale. Je peux dire que ce v\u00e9cu m\u2019a permis d\u2019acqu\u00e9rir le savoir de la hi\u00e9rarchie et de la discipline.&nbsp;Je pratique aussi beaucoup de sport en dehors du campus, notamment la boxe et la musculation qui en plusieurs ann\u00e9es de pratique, me sont devenues indispensables. D\u2019un temp\u00e9rament plut\u00f4t autonome, ces discipline m\u2019ont permis de d\u00e9velopper le go\u00fbt de la pers\u00e9v\u00e9rance, de la rigueur et du respect. Je souhaiterais donc continuer \u00e0 travailler dans la conservation apr\u00e8s mon Master, en retournant en Afrique ou en d\u00e9couvrant de nouveaux pays du Monde.&nbsp; Suivez-moi sur les r\u00e9seaux : Instagram Linkedin Exp\u00e9riences Professionnelles Formations CV\" \/>\n<meta property=\"og:url\" content=\"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/\" \/>\n<meta property=\"og:site_name\" content=\"J\u00e9r\u00f4me ROTH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-11T09:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-1536x768.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/\",\"url\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/\",\"name\":\"Accueil - J\u00e9r\u00f4me ROTH\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/wp-content\\\/uploads\\\/sites\\\/346\\\/2023\\\/11\\\/Accueil-3-compressed-1536x768.jpg\",\"datePublished\":\"2023-10-10T14:03:23+00:00\",\"dateModified\":\"2024-01-11T09:27:06+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/#primaryimage\",\"url\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/wp-content\\\/uploads\\\/sites\\\/346\\\/2023\\\/11\\\/Accueil-3-compressed-scaled.jpg\",\"contentUrl\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/wp-content\\\/uploads\\\/sites\\\/346\\\/2023\\\/11\\\/Accueil-3-compressed-scaled.jpg\",\"width\":2560,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/#website\",\"url\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/\",\"name\":\"J\u00e9r\u00f4me ROTH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/diderot.education\\\/65254e4a287a2-jerome-roth\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - J\u00e9r\u00f4me ROTH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueil - J\u00e9r\u00f4me ROTH","og_description":"Bienvenue sur mon site Qui suis-je ? Je m&rsquo;appelle J\u00e9r\u00f4me, j&rsquo;ai 23 ans et suis \u00e9tudiant en Bachelor de Gestion et Valorisation de la Nature.&nbsp;Ayant v\u00e9cu en Afrique pendant 15 ans, j&rsquo;ai pu r\u00e9sider et voyager dans diff\u00e9rents pays tels que le Congo, le Burkina Faso, le B\u00e9nin et d&rsquo;autres. Cette exp\u00e9rience m&rsquo;a permis d&rsquo;avoir eu&nbsp;r\u00e9guli\u00e8rement la chance de pouvoir suivre des organisations priv\u00e9es et des ONG sp\u00e9cialis\u00e9es dans la pr\u00e9servation de l\u2019environnement et plus particuli\u00e8rement la conservation animale. Je peux dire que ce v\u00e9cu m\u2019a permis d\u2019acqu\u00e9rir le savoir de la hi\u00e9rarchie et de la discipline.&nbsp;Je pratique aussi beaucoup de sport en dehors du campus, notamment la boxe et la musculation qui en plusieurs ann\u00e9es de pratique, me sont devenues indispensables. D\u2019un temp\u00e9rament plut\u00f4t autonome, ces discipline m\u2019ont permis de d\u00e9velopper le go\u00fbt de la pers\u00e9v\u00e9rance, de la rigueur et du respect. Je souhaiterais donc continuer \u00e0 travailler dans la conservation apr\u00e8s mon Master, en retournant en Afrique ou en d\u00e9couvrant de nouveaux pays du Monde.&nbsp; Suivez-moi sur les r\u00e9seaux : Instagram Linkedin Exp\u00e9riences Professionnelles Formations CV","og_url":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/","og_site_name":"J\u00e9r\u00f4me ROTH","article_modified_time":"2024-01-11T09:27:06+00:00","og_image":[{"url":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-1536x768.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/","url":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/","name":"Accueil - J\u00e9r\u00f4me ROTH","isPartOf":{"@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/#website"},"primaryImageOfPage":{"@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/#primaryimage"},"image":{"@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/#primaryimage"},"thumbnailUrl":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-1536x768.jpg","datePublished":"2023-10-10T14:03:23+00:00","dateModified":"2024-01-11T09:27:06+00:00","breadcrumb":{"@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/#primaryimage","url":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-scaled.jpg","contentUrl":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-content\/uploads\/sites\/346\/2023\/11\/Accueil-3-compressed-scaled.jpg","width":2560,"height":1280},{"@type":"BreadcrumbList","@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/#website","url":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/","name":"J\u00e9r\u00f4me ROTH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/users\/348"}],"replies":[{"embeddable":true,"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":42,"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":205,"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/pages\/12\/revisions\/205"}],"wp:attachment":[{"href":"http:\/\/diderot.education\/65254e4a287a2-jerome-roth\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}